{"id":615,"date":"2016-02-19T20:51:10","date_gmt":"2016-02-19T19:51:10","guid":{"rendered":"http:\/\/www.netexpertise.eu\/fr\/?p=615"},"modified":"2021-10-28T07:14:43","modified_gmt":"2021-10-28T06:14:43","slug":"ssh-shell-par-defaut-et-historique-des-commandes-sur-as400","status":"publish","type":"post","link":"http:\/\/www.netexpertise.eu\/fr\/systeme\/as400\/ssh-shell-par-defaut-et-historique-des-commandes-sur-as400.html","title":{"rendered":"SSH, Shell par d\u00e9faut et Historique des Commandes sur AS400"},"content":{"rendered":"\n<p>QSHELL et PASE sur <a href=\"https:\/\/www.netexpertise.eu\/fr\/tag\/ibm-i\">IBM i<\/a> sont des outils int\u00e9ressants mais restent limit\u00e9s par la fen\u00eatre 5250 de taille fixe et sans ascenseur. Voyons comment les rendre plus agr\u00e9ables avec une connexion s\u00e9curis\u00e9e SSH et quelques astuces.<br>&nbsp;<\/p>\n\n\n\n<h3>Lancer le demon SSH<\/h3>\n\n\n\n<p>Consid\u00e9rons que SSH est d\u00e9j\u00e0 install\u00e9 sur votre AS400 c&rsquo;est-\u00e0-dire que vous avez 5733SC1 (OpenSSH, OpenSSL, zlib) dans LICPGM, vous pouvez d\u00e9marrer le demon SSH avec cette commande:<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code lang=\"bash\" class=\"language-bash\">STRTCPSVR SERVER(*SSHD)<\/code><\/pre>\n\n\n\n<p>&nbsp;<br>Il ne semble pas y avoir d&rsquo;option autostart pour le serveur TCP SSH.<br>J&rsquo;ai fini par ajouter la commande au programme de d\u00e9marrage <a href=\"\/fr\/systeme\/as400\/modifier-programme-demarrage-qstrup.html\">QSTRUP<\/a> pour que le serveur SSH d\u00e9marre automatiquement \u00e0 l&rsquo;IPL. Vous pouvez vous connecter \u00e0 votre AS400 avec <a href=\"http:\/\/www.putty.org\">Putty<\/a>, t\u00e9l\u00e9chargeable gratuitement.<br>&nbsp;<\/p>\n\n\n\n<h3>Shell SSH par d\u00e9faut<\/h3>\n\n\n\n<p>Le shell par d\u00e9faut est bsh qui est assez limit\u00e9 et peu commun sur d&rsquo;autres syst\u00e8mes d&rsquo;exploitation. Il peut \u00eatre chang\u00e9 dans le fichier sshd_config file (situ\u00e9 dans \/QOpenSys\/QIBM\/UserData\/SC1\/OpenSSH\/openssh-4.7p1\/etc) en y ajoutant<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code lang=\"bash\" class=\"language-bash\">#ibm pase for IBM i shell\nibmpaseforishell \/QOpenSys\/usr\/bin\/ksh<\/code><\/pre>\n\n\n\n<p>comme mentionn\u00e9 sur le <a href=\"http:\/\/www-01.ibm.com\/support\/docview.wss?uid=nas8N1011555\">site web IBM<\/a>.<br>&nbsp;<br>ksh est aussi requis pour avoir l&rsquo;historique des commandes dans le terminal.<br>&nbsp;<\/p>\n\n\n\n<h3>Historique de commandes<\/h3>\n\n\n\n<p>Une fois que ksh est le shell par d\u00e9faut, vous pouvez configurer les touches fl\u00e9ch\u00e9es pour naviguer dans l&rsquo;historique des commandes. Plus besoin de retaper les commandes encore et toujours!<br><br>Dans le r\u00e9pertoire maison, cr\u00e9ez un fichier .profile qui est charg\u00e9 \u00e0 chaque fois que vous vous connectez \u00e0 l&rsquo;AS400 en SSH:<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code lang=\"bash\" class=\"language-bash\">if [[ $SHELL = \"\/QOpenSys\/usr\/bin\/ksh\" ]]; then\n  set -o emacs\n  alias __A=`echo \"\\020\"`     # up arrow = ^p = back a command\n  alias __B=`echo \"\\016\"`     # down arrow = ^n = down a command\n  alias __C=`echo \"\\006\"`     # right arrow = ^f = forward a character\n  alias __D=`echo \"\\002\"`     # left arrow = ^b = back a character\n  alias __H=`echo \"\\001\"`     # home = ^a = start of line\n  alias __Y=`echo \"\\005\"`     # end = ^e = end of line\nfi<\/code><\/pre>\n\n\n\n<p><br>Red\u00e9marrez le demon SSH dela m\u00eame mani\u00e8re que vous l&rsquo;avez d\u00e9marr\u00e9 et reconnectez-vous.<br>Sur la 1re ligne, nous v\u00e9rifions que le shell est bien ksh puisque les changements faits ne s&rsquo;appliquent qu&rsquo;aux connexions SSH uniquement. Le .profile est aussi charg\u00e9 par QSH et PASE (QP2TERM) mais leur shell par d\u00e9faut n&rsquo;est pas ksh.<br>&nbsp;<br>Se connecter avec Putty est bien plus pratique que d&rsquo;appeler QP2TERM dans une fen\u00eatre 5250 \u00e0 taille fixe!<br>Vous pouvez faire la m\u00eame chose avec bash s&rsquo;il a \u00e9t\u00e9 install\u00e9 sur votre system. Indication: Installer 5733OPS Option 3, gcc est livr\u00e9 avec bash, perl ou encore rpm en postintallation.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>QSHELL et PASE sur IBM i sont des outils int\u00e9ressants mais restent limit\u00e9s par la fen\u00eatre 5250 de taille fixe et sans ascenseur. Voyons comment les rendre plus agr\u00e9ables avec une connexion s\u00e9curis\u00e9e SSH et quelques astuces.&nbsp; Lancer le demon SSH Consid\u00e9rons que SSH est d\u00e9j\u00e0 install\u00e9 sur votre AS400 c&rsquo;est-\u00e0-dire que vous avez 5733SC1 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[226,163],"tags":[416,424,250,308,195,415],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.13 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Netexpertise - SSH, Shell par d\u00e9faut et Historique des Commandes sur AS400<\/title>\n<meta name=\"description\" content=\"Configurez SSH, avec ksh ou bash comme shells par d\u00e9faut, et b\u00e9n\u00e9ficiez du rappel de commandes sur la plate-forme AS400\/IBM i\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.netexpertise.eu\/fr\/systeme\/as400\/ssh-shell-par-defaut-et-historique-des-commandes-sur-as400.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Netexpertise - SSH, Shell par d\u00e9faut et Historique des Commandes sur AS400\" \/>\n<meta property=\"og:description\" content=\"Configurez SSH, avec ksh ou bash comme shells par d\u00e9faut, et b\u00e9n\u00e9ficiez du rappel de commandes sur la plate-forme AS400\/IBM i\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.netexpertise.eu\/fr\/systeme\/as400\/ssh-shell-par-defaut-et-historique-des-commandes-sur-as400.html\" \/>\n<meta property=\"og:site_name\" content=\"Netexpertise\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-19T19:51:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-28T06:14:43+00:00\" \/>\n<meta name=\"author\" content=\"dave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@netexpertise\" \/>\n<meta name=\"twitter:site\" content=\"@netexpertise\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.netexpertise.eu\/fr\/systeme\/as400\/ssh-shell-par-defaut-et-historique-des-commandes-sur-as400.html\",\"url\":\"https:\/\/www.netexpertise.eu\/fr\/systeme\/as400\/ssh-shell-par-defaut-et-historique-des-commandes-sur-as400.html\",\"name\":\"Netexpertise - SSH, Shell par d\u00e9faut et Historique des Commandes sur AS400\",\"isPartOf\":{\"@id\":\"https:\/\/www.netexpertise.eu\/fr\/#website\"},\"datePublished\":\"2016-02-19T19:51:10+00:00\",\"dateModified\":\"2021-10-28T06:14:43+00:00\",\"author\":{\"@id\":\"https:\/\/www.netexpertise.eu\/fr\/#\/schema\/person\/e398f0307e2b167f6b884c4953be2632\"},\"description\":\"Configurez SSH, avec ksh ou bash comme shells par d\u00e9faut, et b\u00e9n\u00e9ficiez du rappel de commandes sur la plate-forme AS400\/IBM i\",\"breadcrumb\":{\"@id\":\"https:\/\/www.netexpertise.eu\/fr\/systeme\/as400\/ssh-shell-par-defaut-et-historique-des-commandes-sur-as400.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.netexpertise.eu\/fr\/systeme\/as400\/ssh-shell-par-defaut-et-historique-des-commandes-sur-as400.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.netexpertise.eu\/fr\/systeme\/as400\/ssh-shell-par-defaut-et-historique-des-commandes-sur-as400.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.netexpertise.eu\/fr\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SSH, Shell par d\u00e9faut et Historique des Commandes sur AS400\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.netexpertise.eu\/fr\/#website\",\"url\":\"https:\/\/www.netexpertise.eu\/fr\/\",\"name\":\"Netexpertise\",\"description\":\"Syst\u00e8mes \/ R\u00e9seaux \/ DevOps\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.netexpertise.eu\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.netexpertise.eu\/fr\/#\/schema\/person\/e398f0307e2b167f6b884c4953be2632\",\"name\":\"dave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.netexpertise.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/1.gravatar.com\/avatar\/1129916e1f4955bd632f27f836f64e55?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/1.gravatar.com\/avatar\/1129916e1f4955bd632f27f836f64e55?s=96&d=mm&r=g\",\"caption\":\"dave\"},\"sameAs\":[\"http:\/\/www.netexpertise.eu\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Netexpertise - SSH, Shell par d\u00e9faut et Historique des Commandes sur AS400","description":"Configurez SSH, avec ksh ou bash comme shells par d\u00e9faut, et b\u00e9n\u00e9ficiez du rappel de commandes sur la plate-forme AS400\/IBM i","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.netexpertise.eu\/fr\/systeme\/as400\/ssh-shell-par-defaut-et-historique-des-commandes-sur-as400.html","og_locale":"fr_FR","og_type":"article","og_title":"Netexpertise - SSH, Shell par d\u00e9faut et Historique des Commandes sur AS400","og_description":"Configurez SSH, avec ksh ou bash comme shells par d\u00e9faut, et b\u00e9n\u00e9ficiez du rappel de commandes sur la plate-forme AS400\/IBM i","og_url":"https:\/\/www.netexpertise.eu\/fr\/systeme\/as400\/ssh-shell-par-defaut-et-historique-des-commandes-sur-as400.html","og_site_name":"Netexpertise","article_published_time":"2016-02-19T19:51:10+00:00","article_modified_time":"2021-10-28T06:14:43+00:00","author":"dave","twitter_card":"summary_large_image","twitter_creator":"@netexpertise","twitter_site":"@netexpertise","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.netexpertise.eu\/fr\/systeme\/as400\/ssh-shell-par-defaut-et-historique-des-commandes-sur-as400.html","url":"https:\/\/www.netexpertise.eu\/fr\/systeme\/as400\/ssh-shell-par-defaut-et-historique-des-commandes-sur-as400.html","name":"Netexpertise - SSH, Shell par d\u00e9faut et Historique des Commandes sur AS400","isPartOf":{"@id":"https:\/\/www.netexpertise.eu\/fr\/#website"},"datePublished":"2016-02-19T19:51:10+00:00","dateModified":"2021-10-28T06:14:43+00:00","author":{"@id":"https:\/\/www.netexpertise.eu\/fr\/#\/schema\/person\/e398f0307e2b167f6b884c4953be2632"},"description":"Configurez SSH, avec ksh ou bash comme shells par d\u00e9faut, et b\u00e9n\u00e9ficiez du rappel de commandes sur la plate-forme AS400\/IBM i","breadcrumb":{"@id":"https:\/\/www.netexpertise.eu\/fr\/systeme\/as400\/ssh-shell-par-defaut-et-historique-des-commandes-sur-as400.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.netexpertise.eu\/fr\/systeme\/as400\/ssh-shell-par-defaut-et-historique-des-commandes-sur-as400.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.netexpertise.eu\/fr\/systeme\/as400\/ssh-shell-par-defaut-et-historique-des-commandes-sur-as400.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.netexpertise.eu\/fr"},{"@type":"ListItem","position":2,"name":"SSH, Shell par d\u00e9faut et Historique des Commandes sur AS400"}]},{"@type":"WebSite","@id":"https:\/\/www.netexpertise.eu\/fr\/#website","url":"https:\/\/www.netexpertise.eu\/fr\/","name":"Netexpertise","description":"Syst\u00e8mes \/ R\u00e9seaux \/ DevOps","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.netexpertise.eu\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.netexpertise.eu\/fr\/#\/schema\/person\/e398f0307e2b167f6b884c4953be2632","name":"dave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.netexpertise.eu\/fr\/#\/schema\/person\/image\/","url":"http:\/\/1.gravatar.com\/avatar\/1129916e1f4955bd632f27f836f64e55?s=96&d=mm&r=g","contentUrl":"http:\/\/1.gravatar.com\/avatar\/1129916e1f4955bd632f27f836f64e55?s=96&d=mm&r=g","caption":"dave"},"sameAs":["http:\/\/www.netexpertise.eu"]}]}},"_links":{"self":[{"href":"http:\/\/www.netexpertise.eu\/fr\/wp-json\/wp\/v2\/posts\/615"}],"collection":[{"href":"http:\/\/www.netexpertise.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.netexpertise.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.netexpertise.eu\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.netexpertise.eu\/fr\/wp-json\/wp\/v2\/comments?post=615"}],"version-history":[{"count":0,"href":"http:\/\/www.netexpertise.eu\/fr\/wp-json\/wp\/v2\/posts\/615\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.netexpertise.eu\/fr\/wp-json\/wp\/v2\/media?parent=615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.netexpertise.eu\/fr\/wp-json\/wp\/v2\/categories?post=615"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.netexpertise.eu\/fr\/wp-json\/wp\/v2\/tags?post=615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}