{"id":587,"date":"2015-04-24T21:45:36","date_gmt":"2015-04-24T20:45:36","guid":{"rendered":"http:\/\/www.netexpertise.eu\/fr\/?p=587"},"modified":"2021-10-11T21:35:20","modified_gmt":"2021-10-11T20:35:20","slug":"deploiement-du-client-access-ibm-iseries-par-gpo","status":"publish","type":"post","link":"http:\/\/www.netexpertise.eu\/fr\/systeme\/as400\/deploiement-du-client-access-ibm-iseries-par-gpo.html","title":{"rendered":"D\u00e9ployer le Client Access IBM iSeries par GPO"},"content":{"rendered":"\n<p>Le client access peut se d\u00e9ployer par <a href=\"\/fr\/tag\/gpo\">GPO<\/a> gr\u00e2ce au fichier MSI fourni dans le r\u00e9pertoire d&rsquo;installation. Vous devrez n\u00e9anmoins cr\u00e9er un fichier MST pour l&rsquo;accompagner lors du d\u00e9ploiement.<\/p>\n\n\n\n<h3><br>Cr\u00e9er un Fichier de Transformation<\/h3>\n\n\n\n<p>Un fichier de transformation contient des param\u00e8tres personnalis\u00e9s que vous pouvez appliquer en d\u00e9ployant un logiciel par GPO. Le MSI n&rsquo;a ainsi pas besoin d&rsquo;\u00eatre modifi\u00e9.<br>&nbsp;<br>T\u00e9l\u00e9chargez out d&rsquo;abord <a href=\"http:\/\/www.instedit.com\">Instedit<\/a> pour personnaliser le fichier MSI.<br>Ex\u00e9cutez Instedit et cliquez sur Fichier -&gt; Ouvrir et naviguez vers image32\\cwbinstall.msi. Le MST (fichier Transform) s&rsquo;appliquera aussi au package 64 bits un peu plus tard.<br>Dans le menu, cliquez Transform -&gt; New Transform<br>Cr\u00e9ez Transform.mst dans le m\u00eame r\u00e9pertoire.<br>&nbsp;<br>Nous allons maintenant modifier le MST.<br>Cliquez sur la table Property, puis sur la partie droite, clic droit -&gt; Add row<br>Saisissez les propri\u00e9t\u00e9s et valeurs.<br>Ex: CWBPrimaryLang\/MRI2928 pour avoir le Fran\u00e7ais en langue par d\u00e9faut.<br>Cliquez ensuite \u00ab\u00a0Enregistrer\u00a0\u00bb dans le menu fichier. Toutes les modifications seront sauvegard\u00e9es dans le fichier MST. Le MSI n&rsquo;a subit aucune modification.<br><br><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img src=\"\/images\/Client_Access_Transform.png\" alt=\"Modifier le MST avec Insedit\"\/><\/figure>\n\n\n\n<p><br>De nombreux param\u00e8tres peuvent \u00eatre personnalis\u00e9s. Une liste des propri\u00e9t\u00e9s publiques est disponible sur<br><a href=\"http:\/\/pic.dhe.ibm.com\/infocenter\/iseries\/v7r1m0\/topic\/rzaij\/rzaijpblcprop.htm\">http:\/\/pic.dhe.ibm.com\/infocenter\/iseries\/v7r1m0\/topic\/rzaij\/rzaijpblcprop.htm<\/a><br>&nbsp;<br>Vous trouverez des propri\u00e9t\u00e9s int\u00e9ressantes que vous pouvez modifier dans la table Property:<br>CWBInstallType: Complete\/Custom\/PC5250User (valide seulement \u00e0 la premi\u00e8re installation)<br>CWBPrimaryLang: MRI2928<br>Dans la tables Feature: Mettez le champ level \u00e0 1 pour les fonctionnalit\u00e9s que vous voulez installer.<br>La liste compl\u00e8te de ces fonctionnalit\u00e9s est disponible sur<br><a href=\"http:\/\/www-01.ibm.com\/support\/knowledgecenter\/ssw_ibm_i_71\/rzaij\/rzaijfeattree.htm\">http:\/\/www-01.ibm.com\/support\/knowledgecenter\/ssw_ibm_i_71\/rzaij\/rzaijfeattree.htm<\/a><br>&nbsp;<br>Note: Si le Client Access iSeries est d\u00e9j\u00e0 install\u00e9 sur l&rsquo;ordinateur ex\u00e9cutant la GPO, seules les fonctionnalit\u00e9s d\u00e9j\u00e0 install\u00e9es seront prises en compte. Le logiciel ne fera que se mettre \u00e0 jour. Un peu dommage!<br>Il existe 2 fa\u00e7ons de contourner ce comportement:<br>&#8211; D\u00e9sinstaller Client Access et ex\u00e9cuter la GPO avec les nouvelles fonctionnalit\u00e9s list\u00e9es dans le fichier MST.<br>&#8211; Ex\u00e9cuter \u00e0 la main msiexec \/i cwbinstall.msi ADDLOCAL=feature (o\u00f9 feature est la fonctionnalit\u00e9 \u00e0 ajouter)<br>&nbsp;<br>Note: L&rsquo;installation et le menu \u00ab\u00a0Tous les programmes\u00a0\u00bb s&rsquo;afficheront en Anglais comme expliqu\u00e9 sur <a href=\"http:\/\/pic.dhe.ibm.com\/infocenter\/iseries\/v6r1m0\/index.jsp?topic=\/rzaij\/rzaijinscnsd.htm\">IBM<\/a>. La s\u00e9lection de la langue est disponible uniquement en ex\u00e9cutant setup.exe. Quoi qu&rsquo;il en soit, la barre de menu dans les applications sera install\u00e9e dans la langue d\u00e9finie dans CWBPrimaryLang.<br>&nbsp;<\/p>\n\n\n\n<h3>Comment utiliser le MST?<\/h3>\n\n\n\n<p>Avant de cr\u00e9er la GPO, vous pouvez ex\u00e9cuter le fichier de transformation sur une machine de test en ligne de commande pour vous assurer que tout fonctionne correctement:<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code lang=\"powershell\" class=\"language-powershell\">msiexec \/i cwbinstall.msi TRANSFORMS=Transform.mst<\/code><\/pre>\n\n\n\n<p><br>Si tout se passe bien, vous pouvez maintenant cr\u00e9er un objet de strat\u00e9gie de groupe.<br><br>1. Cr\u00e9ez un nouveau paquet d&rsquo;installation logiciel dans le noeud param\u00e8tres ordinateur de l&rsquo;\u00e9diteur de GPO.<br>2. S\u00e9lectionnez le fichier MSI cwbinstall, puis cliquez Avanc\u00e9 (C&rsquo;est le SEUL moment que vous pouvez appliquer la transformation au package).<br>3. Pour les installations 32 bits, dans l&rsquo;onglet D\u00e9ploiement, cliquez Avanc\u00e9, et d\u00e9cochez \u00ab\u00a0Rendre cette application 32 bits X86 compatibles sur les machines 64\u00a0\u00bb<br>3. Sur l&rsquo;onglet Modifications, cliquez Ajouter et s\u00e9lectionnez le fichier MST cr\u00e9\u00e9 pr\u00e9c\u00e9demment.<br>4. Si vous avez des OS 32 et 64 bits sur votre r\u00e9seau, ajoutez un second logiciel dans la m\u00eame GPO, et s\u00e9lectionnez l&rsquo;application iSeries 64 bits.<br>Le syst\u00e8me choisira automatiquement la bonne version lors de l&rsquo;application de la GPO<br>&nbsp;<\/p>\n\n\n\n<h3>Service Packs et Pr\u00e9requis<\/h3>\n\n\n\n<p>Pour plus de stabilit\u00e9, vous devriez installer les derniers service packs iSeries Client Access service pack par dessus la derni\u00e8re version.<br>T\u00e9l\u00e9chargez Microsoft Visual C++ 2005 Redistributable SP1 Security update &#8211; C&rsquo;est un pr\u00e9requis du service pack &#8211; vcredist_x86.EXE et vcredist_x64.EXE sur <a href=\"http:\/\/www.microsoft.com\/en-us\/download\/details.aspx?id=26347\">Microsoft<\/a>.<br>T\u00e9l\u00e9chargez les derniers service packs 32 et 64 bits sur la <a href=\"http:\/\/www-03.ibm.com\/systems\/power\/software\/i\/access\/windows_sp.html\">page de t\u00e9l\u00e9chargement des SP IBM<\/a>.<br>Extrayez vcredist_xXX.exe avec 7zip ou un autre logiciel pour obtenir les fichiers MSI et CAB.<br>&nbsp;<br>Pr\u00e9installez l&rsquo;ex\u00e9cutable du service pack sur un ordinateur et choisissez d&rsquo;extraire les fichiers dans un dossier permanent. Copiez le contenu du dossier dans votre image d&rsquo;installation par d\u00e9faut, en \u00e9crasant les anciens fichiers.<br>Pour vcredist, cr\u00e9ez une nouvelle GPO avec les MSI 32 et 64 bits (Ne d\u00e9cochez pas la compatibilit\u00e9 32 bits puisque les OS 64 bits ont besoin de Visual C++ 32 et 64).<br><br><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img src=\"\/images\/Client_Access_GPO.png\" alt=\"Changer l'ordre des GPO\"\/><\/figure><\/div>\n\n\n\n<p><br>Changez l&rsquo;ordre des GPO pour que le client Access s&rsquo;ex\u00e9cute apr\u00e8s vcredist: Cliquez sur l&rsquo;OU; Dans le panneau de droite, mettez le Client Access en position 1 (l&rsquo;ordre est invers\u00e9, la 1re ligne s&rsquo;ex\u00e9cute en dernier!)<br>Red\u00e9ployez la GPO du Client Access avec le service pack int\u00e9gr\u00e9.<\/p>\n\n\n\n<h3><br>V\u00e9rification  du d\u00e9ploiement avec RSOP<\/h3>\n\n\n\n<p>Vous pouvez v\u00e9rifier que le d\u00e9ploiement s&rsquo;est bien pass\u00e9 avec les outils habituels Microsoft comme rsop.msc ou gpresult.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le client access peut se d\u00e9ployer par GPO gr\u00e2ce au fichier MSI fourni dans le r\u00e9pertoire d&rsquo;installation. Vous devrez n\u00e9anmoins cr\u00e9er un fichier MST pour l&rsquo;accompagner lors du d\u00e9ploiement. Cr\u00e9er un Fichier de Transformation Un fichier de transformation contient des param\u00e8tres personnalis\u00e9s que vous pouvez appliquer en d\u00e9ployant un logiciel par GPO. Le MSI n&rsquo;a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[226],"tags":[416,394,396,424,250,411],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.13 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Netexpertise - D\u00e9ployer le Client Access IBM iSeries par GPO<\/title>\n<meta name=\"description\" content=\"D\u00e9ployez le Client Access IBM iSeries par GPO et personnalisez la langue et l&#039;installation avec le MSI et un fichier transform MST\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.netexpertise.eu\/fr\/systeme\/as400\/deploiement-du-client-access-ibm-iseries-par-gpo.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Netexpertise - D\u00e9ployer le Client Access IBM iSeries par GPO\" \/>\n<meta property=\"og:description\" content=\"D\u00e9ployez le Client Access IBM iSeries par GPO et personnalisez la langue et l&#039;installation avec le MSI et un fichier transform MST\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.netexpertise.eu\/fr\/systeme\/as400\/deploiement-du-client-access-ibm-iseries-par-gpo.html\" \/>\n<meta property=\"og:site_name\" content=\"Netexpertise\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-24T20:45:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-11T20:35:20+00:00\" \/>\n<meta name=\"author\" content=\"dave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@netexpertise\" \/>\n<meta name=\"twitter:site\" content=\"@netexpertise\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.netexpertise.eu\/fr\/systeme\/as400\/deploiement-du-client-access-ibm-iseries-par-gpo.html\",\"url\":\"https:\/\/www.netexpertise.eu\/fr\/systeme\/as400\/deploiement-du-client-access-ibm-iseries-par-gpo.html\",\"name\":\"Netexpertise - D\u00e9ployer le Client Access IBM iSeries par GPO\",\"isPartOf\":{\"@id\":\"https:\/\/www.netexpertise.eu\/fr\/#website\"},\"datePublished\":\"2015-04-24T20:45:36+00:00\",\"dateModified\":\"2021-10-11T20:35:20+00:00\",\"author\":{\"@id\":\"https:\/\/www.netexpertise.eu\/fr\/#\/schema\/person\/e398f0307e2b167f6b884c4953be2632\"},\"description\":\"D\u00e9ployez le Client Access IBM iSeries par GPO et personnalisez la langue et l'installation avec le MSI et un fichier transform MST\",\"breadcrumb\":{\"@id\":\"https:\/\/www.netexpertise.eu\/fr\/systeme\/as400\/deploiement-du-client-access-ibm-iseries-par-gpo.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.netexpertise.eu\/fr\/systeme\/as400\/deploiement-du-client-access-ibm-iseries-par-gpo.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.netexpertise.eu\/fr\/systeme\/as400\/deploiement-du-client-access-ibm-iseries-par-gpo.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.netexpertise.eu\/fr\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e9ployer le Client Access IBM iSeries par GPO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.netexpertise.eu\/fr\/#website\",\"url\":\"https:\/\/www.netexpertise.eu\/fr\/\",\"name\":\"Netexpertise\",\"description\":\"Syst\u00e8mes \/ R\u00e9seaux \/ DevOps\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.netexpertise.eu\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.netexpertise.eu\/fr\/#\/schema\/person\/e398f0307e2b167f6b884c4953be2632\",\"name\":\"dave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.netexpertise.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/1.gravatar.com\/avatar\/1129916e1f4955bd632f27f836f64e55?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/1.gravatar.com\/avatar\/1129916e1f4955bd632f27f836f64e55?s=96&d=mm&r=g\",\"caption\":\"dave\"},\"sameAs\":[\"http:\/\/www.netexpertise.eu\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Netexpertise - D\u00e9ployer le Client Access IBM iSeries par GPO","description":"D\u00e9ployez le Client Access IBM iSeries par GPO et personnalisez la langue et l'installation avec le MSI et un fichier transform MST","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.netexpertise.eu\/fr\/systeme\/as400\/deploiement-du-client-access-ibm-iseries-par-gpo.html","og_locale":"fr_FR","og_type":"article","og_title":"Netexpertise - D\u00e9ployer le Client Access IBM iSeries par GPO","og_description":"D\u00e9ployez le Client Access IBM iSeries par GPO et personnalisez la langue et l'installation avec le MSI et un fichier transform MST","og_url":"https:\/\/www.netexpertise.eu\/fr\/systeme\/as400\/deploiement-du-client-access-ibm-iseries-par-gpo.html","og_site_name":"Netexpertise","article_published_time":"2015-04-24T20:45:36+00:00","article_modified_time":"2021-10-11T20:35:20+00:00","author":"dave","twitter_card":"summary_large_image","twitter_creator":"@netexpertise","twitter_site":"@netexpertise","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.netexpertise.eu\/fr\/systeme\/as400\/deploiement-du-client-access-ibm-iseries-par-gpo.html","url":"https:\/\/www.netexpertise.eu\/fr\/systeme\/as400\/deploiement-du-client-access-ibm-iseries-par-gpo.html","name":"Netexpertise - D\u00e9ployer le Client Access IBM iSeries par GPO","isPartOf":{"@id":"https:\/\/www.netexpertise.eu\/fr\/#website"},"datePublished":"2015-04-24T20:45:36+00:00","dateModified":"2021-10-11T20:35:20+00:00","author":{"@id":"https:\/\/www.netexpertise.eu\/fr\/#\/schema\/person\/e398f0307e2b167f6b884c4953be2632"},"description":"D\u00e9ployez le Client Access IBM iSeries par GPO et personnalisez la langue et l'installation avec le MSI et un fichier transform MST","breadcrumb":{"@id":"https:\/\/www.netexpertise.eu\/fr\/systeme\/as400\/deploiement-du-client-access-ibm-iseries-par-gpo.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.netexpertise.eu\/fr\/systeme\/as400\/deploiement-du-client-access-ibm-iseries-par-gpo.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.netexpertise.eu\/fr\/systeme\/as400\/deploiement-du-client-access-ibm-iseries-par-gpo.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.netexpertise.eu\/fr"},{"@type":"ListItem","position":2,"name":"D\u00e9ployer le Client Access IBM iSeries par GPO"}]},{"@type":"WebSite","@id":"https:\/\/www.netexpertise.eu\/fr\/#website","url":"https:\/\/www.netexpertise.eu\/fr\/","name":"Netexpertise","description":"Syst\u00e8mes \/ R\u00e9seaux \/ DevOps","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.netexpertise.eu\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.netexpertise.eu\/fr\/#\/schema\/person\/e398f0307e2b167f6b884c4953be2632","name":"dave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.netexpertise.eu\/fr\/#\/schema\/person\/image\/","url":"http:\/\/1.gravatar.com\/avatar\/1129916e1f4955bd632f27f836f64e55?s=96&d=mm&r=g","contentUrl":"http:\/\/1.gravatar.com\/avatar\/1129916e1f4955bd632f27f836f64e55?s=96&d=mm&r=g","caption":"dave"},"sameAs":["http:\/\/www.netexpertise.eu"]}]}},"_links":{"self":[{"href":"http:\/\/www.netexpertise.eu\/fr\/wp-json\/wp\/v2\/posts\/587"}],"collection":[{"href":"http:\/\/www.netexpertise.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.netexpertise.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.netexpertise.eu\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.netexpertise.eu\/fr\/wp-json\/wp\/v2\/comments?post=587"}],"version-history":[{"count":0,"href":"http:\/\/www.netexpertise.eu\/fr\/wp-json\/wp\/v2\/posts\/587\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.netexpertise.eu\/fr\/wp-json\/wp\/v2\/media?parent=587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.netexpertise.eu\/fr\/wp-json\/wp\/v2\/categories?post=587"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.netexpertise.eu\/fr\/wp-json\/wp\/v2\/tags?post=587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}